{"id":9238,"date":"2025-12-16T11:52:40","date_gmt":"2025-12-16T10:52:40","guid":{"rendered":"https:\/\/maceqen.com\/?post_type=product&#038;p=9238"},"modified":"2025-12-16T11:52:40","modified_gmt":"2025-12-16T10:52:40","slug":"acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen","status":"publish","type":"product","link":"https:\/\/maceqen.com\/en\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/","title":{"rendered":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":9239,"template":"","meta":[],"product_brand":[],"product_cat":[79,72,78],"product_tag":[],"class_list":{"0":"post-9238","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kokrra-ushqim-qen","7":"product_cat-qen","8":"product_cat-ushqim-qen","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen<\/title>\n<meta name=\"description\" content=\"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maceqen.com\/en\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen\" \/>\n<meta property=\"og:description\" content=\"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maceqen.com\/en\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/\" \/>\n<meta property=\"og:site_name\" content=\"Maceqen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61566868653024\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maceqen.com\/wp-content\/uploads\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/\",\"url\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/\",\"name\":\"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maceqen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maceqen.com\\\/wp-content\\\/uploads\\\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp\",\"datePublished\":\"2025-12-16T10:52:40+00:00\",\"description\":\"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maceqen.com\\\/wp-content\\\/uploads\\\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp\",\"contentUrl\":\"https:\\\/\\\/maceqen.com\\\/wp-content\\\/uploads\\\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp\",\"width\":450,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maceqen.com\\\/product\\\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maceqen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/maceqen.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maceqen.com\\\/#website\",\"url\":\"https:\\\/\\\/maceqen.com\\\/\",\"name\":\"Maceqen\",\"description\":\"Maceqen.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/maceqen.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maceqen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maceqen.com\\\/#organization\",\"name\":\"Maceqen\",\"url\":\"https:\\\/\\\/maceqen.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maceqen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maceqen.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/maceqen_transparent-e1724054286368-2.png\",\"contentUrl\":\"https:\\\/\\\/maceqen.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/maceqen_transparent-e1724054286368-2.png\",\"width\":1641,\"height\":727,\"caption\":\"Maceqen\"},\"image\":{\"@id\":\"https:\\\/\\\/maceqen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61566868653024\",\"https:\\\/\\\/www.instagram.com\\\/maceqen_\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen","description":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maceqen.com\/en\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/","og_locale":"en_GB","og_type":"article","og_title":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen","og_description":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen","og_url":"https:\/\/maceqen.com\/en\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/","og_site_name":"Maceqen","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61566868653024","og_image":[{"width":450,"height":450,"url":"https:\/\/maceqen.com\/wp-content\/uploads\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/","url":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/","name":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen","isPartOf":{"@id":"https:\/\/maceqen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/#primaryimage"},"image":{"@id":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/#primaryimage"},"thumbnailUrl":"https:\/\/maceqen.com\/wp-content\/uploads\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp","datePublished":"2025-12-16T10:52:40+00:00","description":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen - Maceqen","breadcrumb":{"@id":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/#primaryimage","url":"https:\/\/maceqen.com\/wp-content\/uploads\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp","contentUrl":"https:\/\/maceqen.com\/wp-content\/uploads\/Grass-Fed-Lamb-Recipe-6kg-Front-Right-FEDIAF.webp","width":450,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/maceqen.com\/product\/acana-singles-grass-fed-lamb-2kg-ushqim-i-thate-per-qen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maceqen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/maceqen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Acana Singles Grass Fed Lamb 2kg. Ushqim i thate per qen"}]},{"@type":"WebSite","@id":"https:\/\/maceqen.com\/#website","url":"https:\/\/maceqen.com\/","name":"Maceqen","description":"Maceqen.com","publisher":{"@id":"https:\/\/maceqen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maceqen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maceqen.com\/#organization","name":"Maceqen","url":"https:\/\/maceqen.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maceqen.com\/#\/schema\/logo\/image\/","url":"https:\/\/maceqen.com\/wp-content\/uploads\/2021\/10\/maceqen_transparent-e1724054286368-2.png","contentUrl":"https:\/\/maceqen.com\/wp-content\/uploads\/2021\/10\/maceqen_transparent-e1724054286368-2.png","width":1641,"height":727,"caption":"Maceqen"},"image":{"@id":"https:\/\/maceqen.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61566868653024","https:\/\/www.instagram.com\/maceqen_\/"]}]}},"_links":{"self":[{"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/product\/9238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/media\/9239"}],"wp:attachment":[{"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/media?parent=9238"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/product_brand?post=9238"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/product_cat?post=9238"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maceqen.com\/en\/wp-json\/wp\/v2\/product_tag?post=9238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}